﻿{"id":2246,"date":"2021-06-01T13:38:25","date_gmt":"2021-06-01T11:38:25","guid":{"rendered":"https:\/\/www.sortlist.es\/blog\/?p=2246"},"modified":"2023-01-31T14:31:27","modified_gmt":"2023-01-31T13:31:27","slug":"el-uso-de-las-redes-sociales","status":"publish","type":"post","link":"https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/","title":{"rendered":"El uso de las redes sociales: \u00bfC\u00f3mo afecta la pandemia a nuestra presencia en l\u00ednea? | Estudio de dos generaciones (2021)"},"content":{"rendered":"<p>Sam es un millennial de 29 a\u00f1os. Con su tel\u00e9fono pegado a la mano, consume contenidos para entretenerse: los v\u00eddeos, los podcasts y el swipe forman parte&nbsp;de su vida cotidiana. Una vida cotidiana que ha cambiado dr\u00e1sticamente en los \u00faltimos 12 meses. Sam, al igual que el 75% de los millennials y la generaci\u00f3n Z, ha <strong>encontrado su hogar en los contenidos digitales<\/strong>, especialmente en <strong>YouTube<\/strong>.<\/p>\n<p>Con el contexto actual, Sam ha sido m\u00e1s activo en las redes sociales (<strong>+64% de compromiso<\/strong>) e incluso ha publicado m\u00e1s contenidos (<strong>+45%<\/strong>) desde que inici\u00f3 la pandemia del coronavirus.<\/p>\n<p>Pero Sam y su generaci\u00f3n no son los \u00fanicos implicados. John y Sarah, sus abuelos, se han inscrito en al menos una red social desde 2020 para mantenerse en contacto con sus seres queridos. Tambi\u00e9n lo ha hecho <strong>m\u00e1s del 30% de la generaci\u00f3n de m\u00e1s de 60 a\u00f1os<\/strong>.<\/p>\n<p><em>El a\u00f1o pasado impuls\u00f3 el consumo digital a nuevos l\u00edmites<\/em>. No solo en nuestro consumo de bienes y servicios, sino tambi\u00e9n en nuestras interacciones con los dem\u00e1s. Nuestra relaci\u00f3n con las herramientas digitales y las redes sociales ha cambiado, al igual que las razones por las que las utilizamos.<\/p>\n<p>Pero, \u00bfc\u00f3mo han evolucionado en t\u00e9rminos concretos?<\/p>\n<h2>Estudio y principales resultados<\/h2>\n<p>En Sortlist, <em>decidimos realizar una encuesta a 1000 usuarios<\/em> en :<\/p>\n<ul>\n<li>Espa\u00f1a,<\/li>\n<li>B\u00e9lgica,<\/li>\n<li>Alemania,<\/li>\n<li>Francia,<\/li>\n<li>Los Pa\u00edses Bajos.<\/li>\n<\/ul>\n<p>El objetivo era descubrir <strong>c\u00f3mo las diferentes generaciones utilizan las redes sociales<\/strong> en respuesta a la pandemia de Covid-19.<\/p>\n<p>Siendo la mitad de los encuestados menores de 35 a\u00f1os y la otra mitad mayores de 60, <strong>observamos las siguientes diferencias<\/strong>:<\/p>\n<ul>\n<li>El <strong>uso<\/strong> de las redes sociales ha <strong>aumentado un 78%<\/strong> entre los millennials y la Generaci\u00f3n Z.<\/li>\n<li>El <strong>25% de los boomers<\/strong> entrevistados se ha <strong>registrado<\/strong> al menos en una red social desde 2020.<\/li>\n<li>El <strong>40%<\/strong> de los entrevistados <strong>prefiere los contenidos de v\u00eddeo<\/strong> a todos los dem\u00e1s formatos de contenido.<\/li>\n<li>El <strong>32%<\/strong> de los menores de 35 a\u00f1os <strong>quiere disminuir su uso<\/strong> de las redes sociales.<\/li>\n<li>Sin embargo, el <strong>72% de los millennials<\/strong> y la Generaci\u00f3n Z no ha <strong>pensado en dejar las redes sociales durante la pandemia<\/strong>.<\/li>\n<li>La <strong>ciencia<\/strong> fue el principal <strong>tema de inter\u00e9s<\/strong> entre los encuestados, con un 29% de publicaciones compartidas relacionadas a esta tem\u00e1tica.<\/li>\n<li>La <strong>plataforma preferida<\/strong> por los <strong>menores<\/strong> de 35 a\u00f1os es <strong>YouTube<\/strong>, mientras que <strong>Facebook<\/strong> es el n\u00famero uno entre los <strong>boomers<\/strong>.<\/li>\n<li>Las generaciones <strong>mayores<\/strong> pasan de media entre <strong>1 y 2 horas diarias <\/strong>menos que los m\u00e1s j\u00f3venes en las redes sociales.<\/li>\n<li>En ambas generaciones, la mayor\u00eda de los entrevistados coincidieron en que las <strong>redes sociales les ayudaron a mantener una vida social durante la pandemia<\/strong>.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2252 aligncenter\" src=\"https:\/\/www.sortlist.es\/blog\/wp-content\/uploads\/sites\/6\/2021\/05\/9.png\" alt=\"es uso de las redes sociales\" width=\"705\" height=\"529\" srcset=\"https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/9.png 1024w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/9-768x576.png 768w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/9-50x38.png 50w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/9-288x216.png 288w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/9-576x432.png 576w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/9-339x254.png 339w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/9-678x509.png 678w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/9-373x280.png 373w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/9-746x560.png 746w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/9-691x518.png 691w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/9-973x730.png 973w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/9-478x359.png 478w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/9-956x717.png 956w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/9-516x387.png 516w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/9-680x510.png 680w\" sizes=\"auto, (max-width: 705px) 100vw, 705px\" \/><\/p>\n<h2>El uso de las redes sociales: M\u00e1s baby boomers y m\u00e1s horas millennial<\/h2>\n<h3>El 78% de los millennials + Gen Z aument\u00f3 su uso de las redes sociales durante la pandemia<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-2255\" src=\"https:\/\/www.sortlist.es\/blog\/wp-content\/uploads\/sites\/6\/2021\/05\/social-media-linkbait-es.png\" alt=\"redes sociales de los millennials\" width=\"441\" height=\"331\" srcset=\"https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/social-media-linkbait-es.png 1024w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/social-media-linkbait-es-768x576.png 768w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/social-media-linkbait-es-50x38.png 50w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/social-media-linkbait-es-288x216.png 288w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/social-media-linkbait-es-576x432.png 576w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/social-media-linkbait-es-339x254.png 339w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/social-media-linkbait-es-678x509.png 678w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/social-media-linkbait-es-373x280.png 373w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/social-media-linkbait-es-746x560.png 746w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/social-media-linkbait-es-691x518.png 691w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/social-media-linkbait-es-973x730.png 973w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/social-media-linkbait-es-478x359.png 478w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/social-media-linkbait-es-956x717.png 956w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/social-media-linkbait-es-516x387.png 516w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/social-media-linkbait-es-680x510.png 680w\" sizes=\"auto, (max-width: 441px) 100vw, 441px\" \/><\/p>\n<p style=\"text-align: left;\">Confinamiento, cuarentena, aislamiento&#8230; nunca hab\u00edamos pasado tanto tiempo dentro de casa con tan poca gente. La reacci\u00f3n de muchos j\u00f3venes ha sido recurrir a las redes sociales para mantenerse ocupados y buscar el contacto social.<\/p>\n<p style=\"text-align: left;\"><strong>El 78% de los entrevistados menores de 35 a\u00f1os afirm\u00f3 haber pasado m\u00e1s tiempo en las redes sociales desde que comenz\u00f3 la pandemia<\/strong>. En la mayor\u00eda de los casos, el objetivo era poder entretenerse.<\/p>\n<h3 style=\"text-align: left;\">El 25% de los entrevistados mayores de 60 a\u00f1os se ha unido a una red social<\/h3>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2257\" src=\"https:\/\/www.sortlist.es\/blog\/wp-content\/uploads\/sites\/6\/2021\/06\/2.png\" alt=\"redes sociales de los boomers\" width=\"371\" height=\"278\" srcset=\"https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/2.png 1024w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/2-768x576.png 768w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/2-50x38.png 50w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/2-288x216.png 288w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/2-576x432.png 576w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/2-339x254.png 339w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/2-678x509.png 678w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/2-373x280.png 373w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/2-746x560.png 746w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/2-691x518.png 691w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/2-973x730.png 973w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/2-478x359.png 478w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/2-956x717.png 956w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/2-516x387.png 516w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/2-680x510.png 680w\" sizes=\"auto, (max-width: 371px) 100vw, 371px\" \/><\/h2>\n<h2><\/h2>\n<p>Tambi\u00e9n descubrimos que el 25% de los entrevistados mayores de 60 a\u00f1os se hab\u00eda registrado en una red social en los \u00faltimos 12 meses. Para compensar el aislamiento, la mayor\u00eda de ellos ha recurrido a herramientas digitales para mantenerse en contacto con sus seres queridos.<\/p>\n<p>Pero estas cifras no son sorprendentes. Entre abril de 2019 y abril de 2020, se registr\u00f3 un <a href=\"https:\/\/blog.hootsuite.com\/simon-kemp-social-media\/\" target=\"_blank\" rel=\"noopener\">aumento de 300 millones de nuevos usuarios<\/a> de medios sociales.&nbsp;Al a\u00f1o siguiente, entre abril de 2020 y abril de 2021, esa cifra era de 520 millones&#8230;<\/p>\n<h2>Intenci\u00f3n de uso: los j\u00f3venes quieren divertirse, los mayores quieren hablar<\/h2>\n<p>Los menores de 35 a\u00f1os buscan entretenimiento y contenidos visuales.<\/p>\n<p>Cuando se les pregunt\u00f3 por qu\u00e9 utilizaban las redes sociales, la respuesta m\u00e1s com\u00fan fue que buscan entretenerse.<\/p>\n<p>En Francia (33%), Alemania (38%) y los Pa\u00edses Bajos (30%), el entretenimiento es la principal motivaci\u00f3n de los menores de 35 a\u00f1os para utilizar las redes sociales.<\/p>\n<p>Sin embargo, la situaci\u00f3n es diferente <strong>en<\/strong> <strong>Espa\u00f1a, ya que solo el 14% de los encuestados utiliza las redes sociales con fines de entretenimiento<\/strong>. Para la mayor\u00eda (37%), mantenerse en contacto con la familia y los amigos es el principal motivador para utilizar las redes sociales.<\/p>\n<p>Esto explicar\u00eda la incre\u00edble cifra del 95% de los espa\u00f1oles menores de 35 a\u00f1os que utilizan WhatsApp.<\/p>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"\u00bfPor qu\u00e9 utilizas las redes sociales?\" src=\"https:\/\/datawrapper.dwcdn.net\/2yfnx\/1\/#?secret=iFzM5HUvGk\" data-secret=\"iFzM5HUvGk\" scrolling=\"no\" frameborder=\"0\" height=\"400\"><\/iframe><\/p>\n<p>En t\u00e9rminos de entretenimiento, el contenido audiovisual es el formato de contenido preferido por los millennials y la Generaci\u00f3n Z.<\/p>\n<p>En concreto, el 35% de los encuestados franceses menores de 35 a\u00f1os afirma que el v\u00eddeo es su formato preferido.<\/p>\n<p>Adem\u00e1s, los <a href=\"https:\/\/www.sortlist.es\/blog\/el-consumo-de-audio\/\" target=\"_blank\" rel=\"noopener\">contenidos de audio<\/a> no se quedan atr\u00e1s y siguen captando una audiencia creciente.<\/p>\n<h3>Los mayores de 60 a\u00f1os quieren compartir y prefieren los contenidos escritos<\/h3>\n<p>En el caso de los boomers, los entrevistados de todos los pa\u00edses respondieron que utilizan principalmente las redes sociales para <strong>mantenerse en contacto con sus seres queridos<\/strong> y mantener una vida social, alcanzando un <strong>41% en Espa\u00f1a<\/strong>.<\/p>\n<p>Adem\u00e1s, en Francia, Alemania y los Pa\u00edses Bajos los mayores de 60 a\u00f1os afirmaron que prefieren los contenidos escritos a cualquier otro formato de contenido digital (42%, 46% y 39%, respectivamente).<\/p>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"\u00bfCu\u00e1l es el formato de contenido digital que m\u00e1s utilizas?\" src=\"https:\/\/datawrapper.dwcdn.net\/L4pcY\/1\/#?secret=g773iIBf6Z\" data-secret=\"g773iIBf6Z\" scrolling=\"no\" frameborder=\"0\" height=\"400\"><\/iframe><\/p>\n<h2>Intenci\u00f3n de uso en medio de una pandemia<\/h2>\n<h3>Las generaciones m\u00e1s j\u00f3venes valoran las herramientas digitales para mantenerse en contacto<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2303 alignright\" src=\"https:\/\/www.sortlist.es\/blog\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-2.png\" alt=\"Importancia de las herramientas digitales\" width=\"392\" height=\"294\" srcset=\"https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-2.png 1024w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-2-768x576.png 768w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-2-50x38.png 50w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-2-288x216.png 288w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-2-576x432.png 576w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-2-339x254.png 339w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-2-678x509.png 678w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-2-373x280.png 373w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-2-746x560.png 746w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-2-691x518.png 691w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-2-973x730.png 973w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-2-478x359.png 478w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-2-956x717.png 956w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-2-516x387.png 516w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-2-680x510.png 680w\" sizes=\"auto, (max-width: 392px) 100vw, 392px\" \/><\/p>\n<p>Es innegable que el Covid-19 ha cambiado nuestras intenciones de uso. Por eso preguntamos a los entrevistados qu\u00e9 importancia tienen las herramientas digitales para mantenerse en contacto con sus seres queridos.<\/p>\n<p><strong>El 18% de los menores de 35 a\u00f1os afirma que las redes sociales son de importancia primordial<\/strong> para mantener su vida social y estar en contacto.<\/p>\n<p>Ir\u00f3nicamente, aunque los boomers dicen que utilizan principalmente las redes sociales para mantenerse en contacto con sus seres queridos, <strong>solo el 10% de ellos dice que es de suma importancia<\/strong>.<\/p>\n<p>Esto demuestra una vez m\u00e1s lo mucho que importan las interacciones sociales para las generaciones m\u00e1s j\u00f3venes, que no solo necesitan entretenerse, sino tambi\u00e9n tener una vida social activa.<\/p>\n<p>As\u00ed que si tienes un familiar de m\u00e1s de 60 a\u00f1os, debes saber que, aunque tenga WhatsApp, prefiere mantener el contacto a la antigua: con bol\u00edgrafo y papel.<\/p>\n<h2>Publicar, gustar, comentar, compartir&#8230; repite.<\/h2>\n<h3>Un 80% de los menores de 35 a\u00f1os nunca ha pensado en dejar las redes sociales<\/h3>\n<p>Adem\u00e1s de aumentar su uso de las redes sociales, la mayor\u00eda de los millennials y miembros de la Generaci\u00f3n Z no pensaron ni una sola vez en dejar las redes sociales durante la pandemia.<\/p>\n<p>El 72% de los encuestados dice no haber pensado nunca en ello. Esta cifra se eleva <strong>al 80% en Espa\u00f1a<\/strong> y Francia.<\/p>\n<p>La tendencia es menos pronunciada en los Pa\u00edses Bajos, donde un 61% de los encuestados afirma no haber pensado en dejar de utilizar las redes sociales.<\/p>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"\u00bfHas pensado alguna vez en dejar las redes sociales durante la pandemia?\" src=\"https:\/\/datawrapper.dwcdn.net\/fPhYr\/1\/#?secret=O5QNwWRlYk\" data-secret=\"O5QNwWRlYk\" scrolling=\"no\" frameborder=\"0\" height=\"400\"><\/iframe><\/p>\n<p>Por lo tanto, si nuestros entrevistados pasan m\u00e1s tiempo en las redes, esto solo puede traducirse en un aumento de su <a href=\"https:\/\/www.sortlist.es\/blog\/calcular-tasa-de-engagement\/\" target=\"_blank\" rel=\"noopener\">tasa de compromiso<\/a>.<\/p>\n<p>Y eso es exactamente lo que encontramos.<\/p>\n<h3>Un 67% de crecimiento en las tasas de compromiso<\/h3>\n<p>Hay una raz\u00f3n por la que las empresas han destinado m\u00e1s presupuesto a su marketing digital este a\u00f1o. En comparaci\u00f3n con 2019, observamos un <a href=\"https:\/\/www.sortlist.com\/insights\" target=\"_blank\" rel=\"noopener\">aumento del 41%<\/a> en la demanda de consultor\u00eda de <a href=\"https:\/\/www.sortlist.es\/social-media\" target=\"_blank\" rel=\"noopener\">medios sociales<\/a>.<\/p>\n<p>El 67% de los millennials y la Generaci\u00f3n Z admiten haber <strong>interactuado m\u00e1s<\/strong> con los contenidos en las redes sociales desde el a\u00f1o pasado. Esto se refiere a:<\/p>\n<ul>\n<li>Comentarios<\/li>\n<li>Likes<\/li>\n<li>Divulgaci\u00f3n<\/li>\n<li>Participaci\u00f3n en concursos<\/li>\n<li>Etc.<\/li>\n<\/ul>\n<p>Los<strong> j\u00f3venes espa\u00f1oles son los m\u00e1s activos<\/strong>, con un <strong>79%<\/strong> declarando haber aumentado su tasa de compromiso. Los j\u00f3venes alemanes se encuentran en el extremo opuesto, con solo un 58%.<\/p>\n<h3><strong>Confinamiento: una oportunidad para compartir contenidos<\/strong><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2301 aligncenter\" src=\"https:\/\/www.sortlist.es\/blog\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-1.png\" alt=\"Compromiso y compartir las redes sociales\" width=\"503\" height=\"377\" srcset=\"https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-1.png 1024w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-1-768x576.png 768w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-1-50x38.png 50w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-1-288x216.png 288w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-1-576x432.png 576w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-1-339x254.png 339w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-1-678x509.png 678w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-1-373x280.png 373w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-1-746x560.png 746w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-1-691x518.png 691w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-1-973x730.png 973w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-1-478x359.png 478w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-1-956x717.png 956w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-1-516x387.png 516w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-1-680x510.png 680w\" sizes=\"auto, (max-width: 503px) 100vw, 503px\" \/><\/p>\n<p>El aumento de la participaci\u00f3n conlleva un aumento de la cantidad de contenidos compartidos.<\/p>\n<p>El 45% de los menores de 35 a\u00f1os encuestados afirma haber compartido m\u00e1s contenidos en las redes sociales desde el a\u00f1o pasado.<\/p>\n<p><strong>Los espa\u00f1oles est\u00e1n a la cabeza con un 55% de respuestas positivas<\/strong>. Los franceses no se quedan atr\u00e1s, con una cifra del 52%.<\/p>\n<p>Los alemanes y los holandeses se sit\u00faan por detr\u00e1s, con un 39% y un 34% respectivamente, de encuestados que dicen haber publicado m\u00e1s contenidos.<\/p>\n<h3>De los selfies a la ciencia<\/h3>\n<p>En colaboraci\u00f3n con <a href=\"https:\/\/explore.meltwater.com\/media-monitoring?utm_source=google&amp;utm_medium=ppc&amp;utm_campaign=advertising-google-11322846632_112639436122&amp;utm_term=g_kwd-978147124_e_meltwater&amp;utm_content=471916200671&amp;locationid=20054&amp;device=c_c&amp;gclid=EAIaIQobChMIx_7prc_p8AIVC_lRCh3WMgrAEAAYASAAEgKw6PD_BwE\" target=\"_blank\" rel=\"noopener\">Meltwater<\/a>, observamos que <strong>el tema que gener\u00f3 m\u00e1s inter\u00e9s en el primer trimestre de 2021 fue la ciencia<\/strong>, comprendiendo un 29% de las publicaciones analizadas.<\/p>\n<p>Adem\u00e1s, el contenido m\u00e1s compartido en las redes sociales por los millennials y la Generaci\u00f3n Z es el <a href=\"https:\/\/www.who.int\/news-room\/feature-stories\/detail\/social-media-covid-19-a-global-study-of-digital-crisis-interaction-among-gen-z-and-millennials\" target=\"_blank\" rel=\"noopener\">contenido cient\u00edfico<\/a>, con casi un <strong>44%<\/strong>.<\/p>\n<p>Parece claro que la pandemia ha influido en los temas a los que la gente presta atenci\u00f3n y que impulsan el debate.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2260 aligncenter\" src=\"https:\/\/www.sortlist.es\/blog\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater.png\" alt=\"Datos exclusivos de Meltwater\" width=\"700\" height=\"308\" srcset=\"https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater.png 1726w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-768x338.png 768w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-1536x675.png 1536w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-50x22.png 50w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-288x127.png 288w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-576x253.png 576w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-339x149.png 339w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-678x298.png 678w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-373x164.png 373w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-746x328.png 746w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-691x304.png 691w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-1382x608.png 1382w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-973x428.png 973w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-1048x461.png 1048w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-478x210.png 478w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-956x420.png 956w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-516x227.png 516w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-1032x454.png 1032w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-680x299.png 680w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/donnees-exlusives-meltwater-1360x598.png 1360w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p style=\"text-align: center;\">Datos exclusivos de Meltwater<\/p>\n<h2>Preferencias generacionales de plataformas<\/h2>\n<h3>\u00bfFacebook? S\u00ed, mi abuela tambi\u00e9n tiene una cuenta&#8230;<\/h3>\n<p>Es obvio que estamos muy apegados a varias herramientas sociales, \u00bfpero cu\u00e1les son nuestras plataformas digitales favoritas? Seg\u00fan estudios recientes, la <strong>popularidad de Facebook sigue reinando<\/strong> y contin\u00faa siendo la plataforma de medios sociales m\u00e1s utilizada del mundo, con <a href=\"https:\/\/datareportal.com\/social-media-users\" target=\"_blank\" rel=\"noopener\">2.797 millones de usuarios activos mensuales<\/a>&#8230; Puede que sea cierto, pero seg\u00fan nuestras estad\u00edsticas, esos casi 3.000 millones de usuarios mensuales probablemente pertenezcan a la generaci\u00f3n del baby boom o anteriores&#8230;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2261 aligncenter\" src=\"https:\/\/www.sortlist.es\/blog\/wp-content\/uploads\/sites\/6\/2021\/06\/4.png\" alt=\"las principales plataformas \" width=\"424\" height=\"318\" srcset=\"https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/4.png 1024w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/4-768x576.png 768w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/4-50x38.png 50w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/4-288x216.png 288w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/4-576x432.png 576w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/4-339x254.png 339w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/4-678x509.png 678w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/4-373x280.png 373w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/4-746x560.png 746w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/4-691x518.png 691w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/4-973x730.png 973w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/4-478x359.png 478w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/4-956x717.png 956w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/4-516x387.png 516w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/4-680x510.png 680w\" sizes=\"auto, (max-width: 424px) 100vw, 424px\" \/><\/p>\n<h3>Facebook #5 entre los menores de 35 a\u00f1os<\/h3>\n<p>Seg\u00fan nuestro estudio, Facebook es solo la quinta red social m\u00e1s utilizada entre los menores de 35 a\u00f1os. En esta generaci\u00f3n, las 3 principales plataformas digitales son:<\/p>\n<ul>\n<li>YouTube (89%)<\/li>\n<li>WhatsApp (83%)<\/li>\n<li>Instagram (82%)<\/li>\n<\/ul>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"\u00bfCu\u00e1les son las plataformas digitales que usas?\" src=\"https:\/\/datawrapper.dwcdn.net\/gqDJP\/1\/#?secret=Trxs1Ixqo2\" data-secret=\"Trxs1Ixqo2\" scrolling=\"no\" frameborder=\"0\" height=\"333\"><\/iframe><\/p>\n<p>A diferencia de los millennials, los mayores de 60 a\u00f1os confirman las investigaciones recientes. M\u00e1s de tres cuartas partes <strong>(77%) de los encuestados revelaron que son activos en Facebook<\/strong>, lo que la convierte en la plataforma de medios sociales m\u00e1s utilizada en su grupo de edad. El <strong>segundo lugar lo ocupa WhatsApp, con un 71%, y el tercero YouTube, con un 67%<\/strong>.<\/p>\n<p>Entre los dos grupos de edad, las <strong>generaciones m\u00e1s j\u00f3venes se sienten m\u00e1s atra\u00eddas por los contenidos de v\u00eddeo<\/strong> que por los contenidos escritos o los canales de comunicaci\u00f3n social.<\/p>\n<h3>YouTubeflix<\/h3>\n<p>En los \u00faltimos a\u00f1os, YouTube ha experimentado un <strong>gran cambio en el comportamiento de sus usuarios<\/strong>. Se ha hablado mucho de c\u00f3mo las plataformas de streaming de v\u00eddeo, como Netflix, Amazon Prime o incluso Hulu, est\u00e1n haciendo frente a la televisi\u00f3n.<\/p>\n<p>Pero, en realidad, no hay que dejar de lado a YouTube. Seg\u00fan un <a href=\"https:\/\/www.thinkwithgoogle.com\/consumer-insights\/consumer-trends\/mobile-youtube-viewing-while-at-home\/\" target=\"_blank\" rel=\"noopener\">estudio realizado por Google<\/a>, YouTube consigue captar la atenci\u00f3n de m\u00e1s adultos en horario de m\u00e1xima audiencia que cualquier otra plataforma.<\/p>\n<p>El 75% de los adultos encuestados afirma que ve v\u00eddeos de YouTube en su casa a trav\u00e9s de sus dispositivos m\u00f3viles. Y seg\u00fan nuestros resultados, para las dos generaciones encuestadas, <strong>YouTube es incluso m\u00e1s utilizado que Netflix<\/strong>.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2262 aligncenter\" src=\"https:\/\/www.sortlist.es\/blog\/wp-content\/uploads\/sites\/6\/2021\/06\/5.png\" alt=\"YouTube vs Netflix\" width=\"462\" height=\"347\" srcset=\"https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/5.png 1024w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/5-768x576.png 768w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/5-50x38.png 50w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/5-288x216.png 288w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/5-576x432.png 576w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/5-339x254.png 339w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/5-678x509.png 678w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/5-373x280.png 373w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/5-746x560.png 746w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/5-691x518.png 691w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/5-973x730.png 973w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/5-478x359.png 478w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/5-956x717.png 956w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/5-516x387.png 516w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/5-680x510.png 680w\" sizes=\"auto, (max-width: 462px) 100vw, 462px\" \/>Su informe semanal sobre el tiempo de pantalla est\u00e1 disponible<\/h2>\n<p>Sabemos ya que los encuestados han pasado m\u00e1s tiempo en las redes sociales este \u00faltimo a\u00f1o. \u00bfPero cu\u00e1nto tiempo pasan realmente en Internet?<\/p>\n<p>De media, un internauta est\u00e1 registrado en <a href=\"https:\/\/wearesocial.com\/blog\/2020\/01\/digital-2020-3-8-billion-people-use-social-media\" target=\"_blank\" rel=\"noopener\">8 redes sociales diferentes<\/a>. En 2020, el usuario promedio pas\u00f3 cerca de 2 horas y 24 minutos al d\u00eda en las redes sociales. Esto supone un aumento del 1,4% (2 minutos) respecto a 2019.<\/p>\n<h2>Los j\u00f3venes franceses y alemanes est\u00e1n siempre activos, pero no sus mayores<\/h2>\n<p>El 28% de los millennials y la Generaci\u00f3n Z pasan de 2 a 3 horas al d\u00eda en las redes sociales.<\/p>\n<p>Se trata de una media, ya que las cifras var\u00edan de un pa\u00eds a otro.<\/p>\n<p><strong>En Espa\u00f1a (36%)<\/strong> y en los Pa\u00edses Bajos (26%), los menores de 35 a\u00f1os pasan <strong>entre 2 y 3 horas al d\u00eda en Internet<\/strong>.<\/p>\n<p>Sin embargo, esta cifra se eleva a m\u00e1s de 4 horas diarias para:<\/p>\n<ul>\n<li>El 30% de los j\u00f3venes franceses<\/li>\n<li>El 34% de los j\u00f3venes alemanes<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2264 aligncenter\" src=\"https:\/\/www.sortlist.es\/blog\/wp-content\/uploads\/sites\/6\/2021\/06\/3.png\" alt=\"Media de horas de redes sociales\" width=\"417\" height=\"313\" srcset=\"https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/3.png 1024w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/3-768x576.png 768w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/3-50x38.png 50w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/3-288x216.png 288w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/3-576x432.png 576w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/3-339x254.png 339w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/3-678x509.png 678w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/3-373x280.png 373w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/3-746x560.png 746w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/3-691x518.png 691w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/3-973x730.png 973w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/3-478x359.png 478w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/3-956x717.png 956w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/3-516x387.png 516w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/3-680x510.png 680w\" sizes=\"auto, (max-width: 417px) 100vw, 417px\" \/><\/p>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"\u00bfCu\u00e1nto tiempo dedicas a las redes sociales?\u00a0\" src=\"https:\/\/datawrapper.dwcdn.net\/PQ5w8\/1\/#?secret=QaEinMgN8Q\" data-secret=\"QaEinMgN8Q\" scrolling=\"no\" frameborder=\"0\" height=\"400\"><\/iframe><\/p>\n<p>En el caso de los mayores de 60 a\u00f1os, hay una fuerte diferencia en la forma de utilizar y pasar el tiempo en las redes sociales. Para esta generaci\u00f3n, la respuesta m\u00e1s com\u00fan, con el 36% de los votos, fue la de <strong>pasar 1-2 horas al d\u00eda en las redes sociales<\/strong>.<\/p>\n<p>Esta fue la respuesta m\u00e1s seleccionada en<strong> Espa\u00f1a (46%)<\/strong> y en los Pa\u00edses Bajos (47%). Sin embargo, en Francia y Alemania, la mayor\u00eda de los boomers afirmaron que pasan menos de una hora al d\u00eda en las redes sociales:<\/p>\n<ul>\n<li>51% para los franceses<\/li>\n<li>38% para los alemanes<\/li>\n<\/ul>\n<p>Esto podr\u00eda estar relacionado con el valor que los encuestados dan a las redes sociales. En Francia y Alemania, <strong>el 40% de los mayores de 60 a\u00f1os piensa que las redes sociales no aportan ning\u00fan valor a su vida cotidiana<\/strong>.<\/p>\n<p>Esto supone un <em>25% m\u00e1s que en Espa\u00f1a<\/em> y los Pa\u00edses Bajos.<\/p>\n<h3>El papel principal del entretenimiento<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2265 alignright\" src=\"https:\/\/www.sortlist.es\/blog\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es.png\" alt=\"Entretenimiento y tiempo dedicado\" width=\"442\" height=\"332\" srcset=\"https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es.png 1024w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-768x576.png 768w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-50x38.png 50w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-288x216.png 288w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-576x432.png 576w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-339x254.png 339w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-678x509.png 678w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-373x280.png 373w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-746x560.png 746w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-691x518.png 691w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-973x730.png 973w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-478x359.png 478w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-956x717.png 956w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-516x387.png 516w, https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/06\/social-media-linkbait-es-680x510.png 680w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/><\/p>\n<p>Hay una explicaci\u00f3n sencilla detr\u00e1s de estas disparidades, no solo entre generaciones, sino tambi\u00e9n entre pa\u00edses.<\/p>\n<p><strong>Cuanto m\u00e1s utiliza una persona las redes sociales para entretenerse, mayor la probabilidad de que pase m\u00e1s tiempo en ellas.&nbsp;<\/strong><\/p>\n<p>Para las generaciones m\u00e1s j\u00f3venes, Francia y Alemania son los dos pa\u00edses donde la gente pasa m\u00e1s tiempo en las redes sociales cada d\u00eda. Pero tambi\u00e9n son los dos pa\u00edses en los que la gente dice utilizar m\u00e1s las redes sociales para entretenerse.<\/p>\n<p>En cuanto a las generaciones mayores, podemos concluir que cuanto m\u00e1s utilice una persona las redes sociales para mantenerse en contacto con su entorno, menos tiempo le dedicar\u00e1. Y esto es en comparaci\u00f3n con alguien que busca entretenimiento.<\/p>\n<h3>El 32% de los menores de 35 a\u00f1os quiere reducir su uso de las redes sociales<\/h3>\n<p>Anteriormente en nuestro estudio, se\u00f1alamos que los millennials y los miembros de la Generaci\u00f3n Z no dejar\u00edan las redes sociales. \u00bfPero qu\u00e9 hay de cambiar sus h\u00e1bitos?<\/p>\n<p>Preguntamos a los entrevistados si <strong>quer\u00edan disminuir su uso de las redes sociales<\/strong>. No es de extra\u00f1ar que Francia (35%) y Alemania (32%) sean los dos pa\u00edses con m\u00e1s respuestas positivas a esta pregunta.<\/p>\n<p>Tambi\u00e9n fue la <em>respuesta m\u00e1s com\u00fan en Espa\u00f1a<\/em> y los Pa\u00edses Bajos.<\/p>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"\u00bfDeseas disminuir el uso de las redes sociales?\u00a0\" src=\"https:\/\/datawrapper.dwcdn.net\/8KmQU\/2\/#?secret=mwH9QbAMbs\" data-secret=\"mwH9QbAMbs\" scrolling=\"no\" frameborder=\"0\" height=\"400\"><\/iframe><\/p>\n<h2>Nuestro millennial Sam&#8230;<\/h2>\n<p>Es innegable que las redes sociales y las herramientas digitales <strong>forman parte de nuestra vida cotidiana<\/strong>. A pesar de las cr\u00edticas que reciben, estas redes tuvieron un papel fundamental en 2020.<\/p>\n<p>Su verdadero valor a\u00f1adido se puso entonces de manifiesto:<\/p>\n<ul>\n<li>Mantener el contacto<\/li>\n<li>Vernos<\/li>\n<li>Interactuar<\/li>\n<li>Y compartir contenidos<\/li>\n<\/ul>\n<p>Mientras que la generaci\u00f3n de Sam ha crecido con estas redes, sus abuelos John y Sarah solo se conectan de vez en cuando para estar en contacto con sus seres queridos.<\/p>\n<p>Aunque Facebook sigue siendo la plataforma preferida por las generaciones mayores, no ser\u00eda sorprendente ver c\u00f3mo prueban otras redes sociales.<\/p>\n<p>TikTok es un ejemplo de ello, y sus v\u00eddeos virales no mienten: TikTok ha acercado a los abuelos a sus nietos, y de forma muy creativa.<\/p>\n<p>Como dice el \u00ababuelo Joe\u00bb en esta entrevista del <a href=\"https:\/\/www.washingtonpost.com\/gdpr-consent\/?next_url=https%3a%2f%2fwww.washingtonpost.com%2flifestyle%2f2020%2f05%2f14%2fgrandparents-are-dancing-with-their-grandkids-tiktok-people-cant-get-enough%2f\" target=\"_blank\" rel=\"noopener\">Washington Post<\/a> sobre sus 4,2 millones de seguidores: \u00abNo lo hago por la fama, lo hago por los buenos momentos con mi nieta\u00bb.<\/p>\n<blockquote class=\"tiktok-embed\" cite=\"https:\/\/www.tiktok.com\/@grandadjoe1933\/video\/6820512721872719110\" data-video-id=\"6820512721872719110\" data-embed-from=\"oembed\" style=\"max-width:605px; min-width:325px;\">\n<section> <a target=\"_blank\" title=\"@grandadjoe1933\" href=\"https:\/\/www.tiktok.com\/@grandadjoe1933?refer=embed\">@grandadjoe1933<\/a> <\/p>\n<p>I was concentrating so hard \ud83d\ude02 @brookepaintain \u2764\ufe0f <a title=\"toosiechallenge\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/toosiechallenge?refer=embed\">#toosiechallenge<\/a> <a title=\"trend\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/trend?refer=embed\">#trend<\/a> <a title=\"grandad\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/grandad?refer=embed\">#grandad<\/a><\/p>\n<p> <a target=\"_blank\" title=\"\u266c Toosie Slide - Drake\" href=\"https:\/\/www.tiktok.com\/music\/Toosie-Slide-6811422424131700738?refer=embed\">\u266c Toosie Slide &#8211; Drake<\/a> <\/section>\n<\/blockquote>\n<p> <script async src=\"https:\/\/www.tiktok.com\/embed.js\"><\/script><\/p>\n<h2>Metodolog\u00eda<\/h2>\n<p>Despu\u00e9s de realizar una encuesta interna dentro de Sortlist para saber si alguno de los 150 empleados conoc\u00eda a alguien mayor de 60 a\u00f1os que se hubiera unido a alguna plataforma de medios sociales este \u00faltimo a\u00f1o, encuestamos a 500 personas menores de 35 a\u00f1os (125 en Espa\u00f1a y Alemania y 63 en Francia, B\u00e9lgica franc\u00f3fona, Pa\u00edses Bajos y B\u00e9lgica flamenca) y a 490 mayores de 60 a\u00f1os (125 en Espa\u00f1a y Alemania, 63 en Francia y B\u00e9lgica franc\u00f3fona, y 53 en Pa\u00edses Bajos y B\u00e9lgica flamenca) para averiguar qu\u00e9 <strong>uso hicieron de las redes sociales durante la pandemia<\/strong> y por qu\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sam es un millennial de 29 a\u00f1os. Con su tel\u00e9fono pegado a la mano, consume contenidos para entretenerse: los v\u00eddeos, los podcasts y el swipe forman parte&nbsp;de su vida cotidiana. Una vida cotidiana que ha cambiado dr\u00e1sticamente en los \u00faltimos 12 meses. Sam, al igual que el 75% de los millennials y la generaci\u00f3n Z, [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":2249,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"_sb_show_comment_boards":false,"content-type":"","om_disable_all_campaigns":false,"_cf_multicollab_revision_bundle":"","footnotes":""},"categories":[69,37],"class_list":["post-2246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sortlist-insights","category-marketing-y-publicidad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudio: Millennials vs. Boomers, el uso de las redes sociales en 2021<\/title>\n<meta name=\"description\" content=\"Descubre c\u00f3mo la pandemia de Covid-19 impactar\u00e1 en el uso de las redes sociales por parte de los Millennials y Boomers en 2021.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudio: Millennials vs. Boomers, el uso de las redes sociales en 2021\" \/>\n<meta property=\"og:description\" content=\"Descubre c\u00f3mo la pandemia de Covid-19 impactar\u00e1 en el uso de las redes sociales por parte de los Millennials y Boomers en 2021.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/\" \/>\n<meta property=\"og:site_name\" content=\"Sortlist Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-01T11:38:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-31T13:31:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sortlist.es\/blog\/wp-content\/uploads\/sites\/6\/2021\/05\/covers-articles-eng-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1747\" \/>\n\t<meta property=\"og:image:height\" content=\"1240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alicia Zambrano Braun\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alicia Zambrano Braun\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/el-uso-de-las-redes-sociales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/el-uso-de-las-redes-sociales\\\/\"},\"author\":{\"name\":\"Alicia Zambrano Braun\",\"@id\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/#\\\/schema\\\/person\\\/585f2d099f68ff3a244c917c2553b5ee\"},\"headline\":\"El uso de las redes sociales: \u00bfC\u00f3mo afecta la pandemia a nuestra presencia en l\u00ednea? | Estudio de dos generaciones (2021)\",\"datePublished\":\"2021-06-01T11:38:25+00:00\",\"dateModified\":\"2023-01-31T13:31:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/el-uso-de-las-redes-sociales\\\/\"},\"wordCount\":2815,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/el-uso-de-las-redes-sociales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.blog.production.sortlist.cloud\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/05\\\/covers-articles-eng-1.png\",\"articleSection\":[\"Sortlist Insights\",\"Marketing y Publicidad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/el-uso-de-las-redes-sociales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/el-uso-de-las-redes-sociales\\\/\",\"url\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/el-uso-de-las-redes-sociales\\\/\",\"name\":\"Estudio: Millennials vs. Boomers, el uso de las redes sociales en 2021\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/el-uso-de-las-redes-sociales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/el-uso-de-las-redes-sociales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.blog.production.sortlist.cloud\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/05\\\/covers-articles-eng-1.png\",\"datePublished\":\"2021-06-01T11:38:25+00:00\",\"dateModified\":\"2023-01-31T13:31:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/#\\\/schema\\\/person\\\/585f2d099f68ff3a244c917c2553b5ee\"},\"description\":\"Descubre c\u00f3mo la pandemia de Covid-19 impactar\u00e1 en el uso de las redes sociales por parte de los Millennials y Boomers en 2021.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/el-uso-de-las-redes-sociales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/el-uso-de-las-redes-sociales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/el-uso-de-las-redes-sociales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.blog.production.sortlist.cloud\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/05\\\/covers-articles-eng-1.png\",\"contentUrl\":\"https:\\\/\\\/cdn.blog.production.sortlist.cloud\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/05\\\/covers-articles-eng-1.png\",\"width\":1747,\"height\":1240,\"caption\":\"el uso de las redes sociales de Sortlist\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/el-uso-de-las-redes-sociales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El uso de las redes sociales: \u00bfC\u00f3mo afecta la pandemia a nuestra presencia en l\u00ednea? | Estudio de dos generaciones (2021)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/\",\"name\":\"Sortlist Blog\",\"description\":\"Nuestras Gu\u00edas de Marketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/#\\\/schema\\\/person\\\/585f2d099f68ff3a244c917c2553b5ee\",\"name\":\"Alicia Zambrano Braun\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.production.sortlist.cloud\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/avatar_user_25_1625132301-96x96.png\",\"url\":\"https:\\\/\\\/blog.production.sortlist.cloud\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/avatar_user_25_1625132301-96x96.png\",\"contentUrl\":\"https:\\\/\\\/blog.production.sortlist.cloud\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/avatar_user_25_1625132301-96x96.png\",\"caption\":\"Alicia Zambrano Braun\"},\"description\":\"Quand Alicia ne cr\u00e9e pas de contenu pour ses blogs fran\u00e7ais ou espagnol, elle trouve l\u2019inspiration sur les r\u00e9seaux sociaux.\u00a0Elle erre sur \u201cCreapils\u201d et \u201cJ\u2019ai un pote dans la com\u201d pour trouver les meilleures id\u00e9es ! Analyser des publicit\u00e9s sympas est son pain quotidien ET... c\u2019est une rockstar du hockey !\",\"url\":\"https:\\\/\\\/www.sortlist.es\\\/blog\\\/author\\\/aliciazambranobraun\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudio: Millennials vs. Boomers, el uso de las redes sociales en 2021","description":"Descubre c\u00f3mo la pandemia de Covid-19 impactar\u00e1 en el uso de las redes sociales por parte de los Millennials y Boomers en 2021.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/","og_locale":"es_ES","og_type":"article","og_title":"Estudio: Millennials vs. Boomers, el uso de las redes sociales en 2021","og_description":"Descubre c\u00f3mo la pandemia de Covid-19 impactar\u00e1 en el uso de las redes sociales por parte de los Millennials y Boomers en 2021.","og_url":"https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/","og_site_name":"Sortlist Blog","article_published_time":"2021-06-01T11:38:25+00:00","article_modified_time":"2023-01-31T13:31:27+00:00","og_image":[{"width":1747,"height":1240,"url":"https:\/\/www.sortlist.es\/blog\/wp-content\/uploads\/sites\/6\/2021\/05\/covers-articles-eng-1.png","type":"image\/png"}],"author":"Alicia Zambrano Braun","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Alicia Zambrano Braun","Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/#article","isPartOf":{"@id":"https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/"},"author":{"name":"Alicia Zambrano Braun","@id":"https:\/\/www.sortlist.es\/blog\/#\/schema\/person\/585f2d099f68ff3a244c917c2553b5ee"},"headline":"El uso de las redes sociales: \u00bfC\u00f3mo afecta la pandemia a nuestra presencia en l\u00ednea? | Estudio de dos generaciones (2021)","datePublished":"2021-06-01T11:38:25+00:00","dateModified":"2023-01-31T13:31:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/"},"wordCount":2815,"commentCount":0,"image":{"@id":"https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/covers-articles-eng-1.png","articleSection":["Sortlist Insights","Marketing y Publicidad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/","url":"https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/","name":"Estudio: Millennials vs. Boomers, el uso de las redes sociales en 2021","isPartOf":{"@id":"https:\/\/www.sortlist.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/#primaryimage"},"image":{"@id":"https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/covers-articles-eng-1.png","datePublished":"2021-06-01T11:38:25+00:00","dateModified":"2023-01-31T13:31:27+00:00","author":{"@id":"https:\/\/www.sortlist.es\/blog\/#\/schema\/person\/585f2d099f68ff3a244c917c2553b5ee"},"description":"Descubre c\u00f3mo la pandemia de Covid-19 impactar\u00e1 en el uso de las redes sociales por parte de los Millennials y Boomers en 2021.","breadcrumb":{"@id":"https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/#primaryimage","url":"https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/covers-articles-eng-1.png","contentUrl":"https:\/\/cdn.blog.production.sortlist.cloud\/wp-content\/uploads\/sites\/6\/2021\/05\/covers-articles-eng-1.png","width":1747,"height":1240,"caption":"el uso de las redes sociales de Sortlist"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sortlist.es\/blog\/el-uso-de-las-redes-sociales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sortlist.es\/blog\/"},{"@type":"ListItem","position":2,"name":"El uso de las redes sociales: \u00bfC\u00f3mo afecta la pandemia a nuestra presencia en l\u00ednea? | Estudio de dos generaciones (2021)"}]},{"@type":"WebSite","@id":"https:\/\/www.sortlist.es\/blog\/#website","url":"https:\/\/www.sortlist.es\/blog\/","name":"Sortlist Blog","description":"Nuestras Gu\u00edas de Marketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sortlist.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.sortlist.es\/blog\/#\/schema\/person\/585f2d099f68ff3a244c917c2553b5ee","name":"Alicia Zambrano Braun","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.production.sortlist.cloud\/wp-content\/uploads\/2021\/07\/avatar_user_25_1625132301-96x96.png","url":"https:\/\/blog.production.sortlist.cloud\/wp-content\/uploads\/2021\/07\/avatar_user_25_1625132301-96x96.png","contentUrl":"https:\/\/blog.production.sortlist.cloud\/wp-content\/uploads\/2021\/07\/avatar_user_25_1625132301-96x96.png","caption":"Alicia Zambrano Braun"},"description":"Quand Alicia ne cr\u00e9e pas de contenu pour ses blogs fran\u00e7ais ou espagnol, elle trouve l\u2019inspiration sur les r\u00e9seaux sociaux.\u00a0Elle erre sur \u201cCreapils\u201d et \u201cJ\u2019ai un pote dans la com\u201d pour trouver les meilleures id\u00e9es ! Analyser des publicit\u00e9s sympas est son pain quotidien ET... c\u2019est une rockstar du hockey !","url":"https:\/\/www.sortlist.es\/blog\/author\/aliciazambranobraun\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sortlist.es\/blog\/wp-json\/wp\/v2\/posts\/2246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sortlist.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sortlist.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sortlist.es\/blog\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sortlist.es\/blog\/wp-json\/wp\/v2\/comments?post=2246"}],"version-history":[{"count":21,"href":"https:\/\/www.sortlist.es\/blog\/wp-json\/wp\/v2\/posts\/2246\/revisions"}],"predecessor-version":[{"id":8900,"href":"https:\/\/www.sortlist.es\/blog\/wp-json\/wp\/v2\/posts\/2246\/revisions\/8900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sortlist.es\/blog\/wp-json\/wp\/v2\/media\/2249"}],"wp:attachment":[{"href":"https:\/\/www.sortlist.es\/blog\/wp-json\/wp\/v2\/media?parent=2246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sortlist.es\/blog\/wp-json\/wp\/v2\/categories?post=2246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}